{"id":2344,"date":"2012-03-01T08:47:23","date_gmt":"2012-03-01T14:47:23","guid":{"rendered":"http:\/\/test7.wrmeadows.com\/?p=2344"},"modified":"2020-02-10T10:23:19","modified_gmt":"2020-02-10T16:23:19","slug":"rezi-weld-lv-state-espanol","status":"publish","type":"post","link":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/","title":{"rendered":"REZI-WELD LV STATE (Espa\u00f1ol)"},"content":{"rendered":"<p><a name=\"ds\"><\/a><\/p>\n<h3 class=\"section\">Hoja de datos del producto<\/h3>\n<p><a href=\"https:\/\/www.wrmeadows.com\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-hdredorang.jpg\" alt=\"Datos de Producto, W. R. MEADOWS\" width=\"680\" height=\"151\" align=\"BOTTOM\" border=\"0\" \/><\/a><\/p>\n<table border=\"0\" width=\"100%\" cellspacing=\"2\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td valign=\"TOP\" width=\"22%\"><strong><span><a href=\"https:\/\/www.wrmeadows.com\/sp\/#3900\">03 01 00<\/a><\/span><\/strong><br \/>\n<strong><span><a href=\"https:\/\/www.wrmeadows.com\/sp\/#3900\">03 64 23<\/a><\/span><\/strong><\/td>\n<td width=\"30%\"><strong><span>392-S &#8211; <\/span><em><span><a href=\"https:\/\/www.wrmeadows.com\/espanol\/data\/392S-esp.pdf\">versi\u00f3n impresa<\/a><\/span><\/em><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>REZI-WELD<sub>\u2122<\/sub> LV STATE<\/strong><br \/>\n<strong>Adhesivo ep\u00f3xico inyectable de viscosidad ultra-baja<\/strong><\/p>\n<p><strong>DESCRIPCI\u00d3N<\/strong><br \/>\nREZI-WELD LV STATE es una resina inyectable estructural, de base ep\u00f3xica y viscosidad ultrabaja, de dos componentes, 100% s\u00f3lidos, que fragua r\u00e1pidamente. Es un sistema de resina ep\u00f3xica de ultrabaja viscosidad, m\u00f3dulo alto, sin solventes, bajo olor, alta resistencia, insensible a la humedad. REZI-WELD LV STATE resiste la mayor\u00eda de los agentes qu\u00edmicos y forma una uni\u00f3n estructural monol\u00edtica con concreto t\u00edpico.<\/p>\n<p>Su baja tensi\u00f3n de superficie facilita la penetraci\u00f3n profunda en grietas finas hasta tama\u00f1o medio. La formulaci\u00f3n 100% de s\u00f3lidos es volum\u00e9tricamente estable, asegurando una uni\u00f3n s\u00f3lida a ambos lados de la grieta.<\/p>\n<p><strong>USOS<\/strong><br \/>\nREZI-WELD LV STATE se ha dise\u00f1ado para alimentaci\u00f3n por gravedad o inyecci\u00f3n a presi\u00f3n. Se ofrece en dos tama\u00f1os de cartuchos para facilitar el uso. Tambi\u00e9n se ofrece en unidades a granel y puede inyectarse usando bombas medidoras de dos componentes. Es apto para inyectar en grietas estructurales finas, que no se muevan en concreto y madera para reparaci\u00f3n a largo plazo. REZI-WELD LV STATE es un mortero ep\u00f3xico econ\u00f3mico y f\u00e1cil de usar para parchar o reparar defectos en sustratos de concreto.<\/p>\n<p><strong>CARACTER\u00cdSTICAS\/VENTAJAS<\/strong><\/p>\n<ul>\n<li>La viscosidad ultrabaja es ideal para inyectar a presi\u00f3n y alimentar por gravedad.<\/li>\n<li>Ventajoso como adhesivo ep\u00f3xico de baja viscosidad.<\/li>\n<li>Une concreto curado a madera, acero o concreto pl\u00e1stico.<\/li>\n<li>Se combina con \u00e1ridos para formar un recubrimiento interior antideslizante.<\/li>\n<li>Resiste los agentes qu\u00edmicos industriales, as\u00ed como el impacto y ataque de la humedad.<\/li>\n<li>Presenta caracter\u00edsticas de baja viscosidad, alto m\u00f3dulo, alta resistencia, autonivelaci\u00f3n.<\/li>\n<li>Se suministra en dos tama\u00f1os convenientes de cartuchos.<\/li>\n<\/ul>\n<p><strong>EMPAQUE<\/strong><br \/>\nCartuchos de 180 ml (6.1 oz.)<br \/>\nCartuchos de 475 ml (16 oz.)<br \/>\nUnidades de 11.4 litros (3 galones)<br \/>\nUnidades de 57 litros (15 galones)<\/p>\n<p><strong>COBERTURA <\/strong><br \/>\nLa cantidad de 3.8 litros (1 gal\u00f3n) cubre aproximadamente 2.1 &#8211; 2.7 m<sup>2<\/sup>\/litro (85 -100 pies<sup>2<\/sup>\/gal.) dependiendo de la porosidad de la superficie y la aplicaci\u00f3n del uso final. La cantidad de 3.8 litros<br \/>\n(1 gal\u00f3n) mezclada 1:1 con \u00e1ridos secos rinde aproximadamente 5735 cm<sup>3<\/sup> (350 pulg.<sup>3<\/sup>) de calafateo.<\/p>\n<p><strong>DURACI\u00d3N EN ALMACENAMIENTO <\/strong><strong><br \/>\n<\/strong>Dos a\u00f1os en envases y cartuchos sin abrir cuando se guarde entre 10 &#8211; 35 \u00b0C (50 &#8211; 95 \u00b0F).<\/p>\n<p><strong>ESPECIFICACIONES <\/strong><\/p>\n<ul>\n<li>ASTM C 881-99 Tipo I, II, IV y V, Grado 1, Clases B &amp; C<\/li>\n<li>AASHTO M 235 Tipo I, II, IV y V, Grado 1, Clases B y C<\/li>\n<\/ul>\n<p>Diferentes aprobaciones de Departamentos de Transporte<\/p>\n<p><strong>DATOS T\u00c9CNICOS<\/strong><\/p>\n<table width=\"100%\" class=\"table\">\n<tbody>\n<tr>\n<td width=\"49%\"><strong>Propiedad<\/strong><br \/>\n7 d\u00edas de curado<br \/>\na 25 \u00b0C (77 \u00b0F)<\/td>\n<td width=\"23%\"><strong>Datos t\u00edpicos<\/strong><\/td>\n<td width=\"27%\"><strong>M\u00e9todo de prueba<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Viscosidad, cps<\/td>\n<td width=\"23%\">450 &#8211; 550<\/td>\n<td width=\"27%\">ASTM C 881<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Resistencia de tensado, psi<\/td>\n<td width=\"23%\">7,200<br \/>\n(49.6 MPa)<\/td>\n<td width=\"27%\">ASTM D 638<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Estiramiento, %<\/td>\n<td width=\"23%\">8.8<\/td>\n<td width=\"27%\">ASTM D 638<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Dureza, Shore D<\/td>\n<td width=\"23%\">85<\/td>\n<td width=\"27%\">ASTM D 2240<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Resistencia a flexi\u00f3n, psi<\/td>\n<td width=\"23%\">8500<br \/>\n(55.2 MPa)<\/td>\n<td width=\"27%\">ASTM D 790<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Resistencia de compresi\u00f3n, psi<\/td>\n<td width=\"23%\">12,000<br \/>\n(82.7 MPa)<\/td>\n<td width=\"27%\">ASTM D 695<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">M\u00f3dulo de compresi\u00f3n, psi<\/td>\n<td width=\"23%\">260,000<br \/>\n(1,800 MPa)<\/td>\n<td width=\"27%\">ASTM D 695<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Resistencia de uni\u00f3n, psi<br \/>\n(2 d\u00edas)<\/td>\n<td width=\"23%\">2,100<br \/>\n(14.4 MPa)<\/td>\n<td width=\"27%\">ASTM C 882<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Resistencia de uni\u00f3n, psi<br \/>\n(14 d\u00edas)<\/td>\n<td width=\"23%\">3,000<br \/>\n(20.6 MPa)<\/td>\n<td width=\"27%\">ASTM C 882<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Temperatura de deflexi\u00f3n t\u00e9rmica<\/td>\n<td width=\"23%\">48 \u00baC<br \/>\n(120 \u00baF)<\/td>\n<td width=\"27%\">ASTM D 648<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Absorci\u00f3n, % (24 horas)<\/td>\n<td width=\"23%\">0.23%<\/td>\n<td width=\"27%\">ASTM D 570<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\">Coeficiente lineal de encogimiento<\/td>\n<td width=\"23%\">0.004<\/td>\n<td width=\"27%\">ASTM D 2566<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\"><strong>Propiedades de componentes<\/strong><\/td>\n<td width=\"23%\"><strong>Resina<\/strong><\/td>\n<td width=\"27%\"><strong><em>Endurecedor<\/em><\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"49%\"><strong>Proporci\u00f3n para mezclar<\/strong><br \/>\n(PBV=Partes por Vol.)<\/td>\n<td width=\"23%\">2 PBV<\/td>\n<td width=\"27%\">1 PBV<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\"><strong>Apariencia<\/strong><\/td>\n<td width=\"23%\">Transparente<\/td>\n<td width=\"27%\">\u00c1mbar<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\"><strong>Duraci\u00f3n<\/strong> (1000 gms)<br \/>\na 21.5 \u00b0C (75 \u00b0F)<\/td>\n<td width=\"23%\">20 -30 Min.<\/td>\n<td width=\"27%\">ASTM C 881<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\"><strong>Tiempo sin pegajosidad <\/strong><br \/>\na 1.9 mm<br \/>\n(30 mil\u00e9simas de pulgada)<br \/>\na 21.1 \u00b0C (70 \u00b0F)<\/td>\n<td width=\"23%\">4-5 Hrs.<\/td>\n<td width=\"27%\">ASTM C 879<\/td>\n<\/tr>\n<tr>\n<td width=\"49%\"><strong>Contenido de compuestos org\u00e1nicos vol\u00e1tiles (VOC)<\/strong><\/td>\n<td width=\"23%\">5 g\/L<\/td>\n<td width=\"27%\">&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Todos los datos t\u00e9cnicos son informaci\u00f3n t\u00edpica, pero pueden variar debido a los m\u00e9todos de prueba, condiciones y operadores.<\/p>\n<p><strong>APLICACI\u00d3N <\/strong><br \/>\n<strong>Preparaci\u00f3n de la superficie &#8230;<\/strong> Todas las superficies a unir deben estar sin agua estancada y completamente limpias de suciedad, \u00f3xido, compuestos de curado, grasa, aceite, pintura, ceras y otros materiales que podr\u00edan impedir una uni\u00f3n \u00f3ptima. El concreto debe limpiarse con abrasi\u00f3n mec\u00e1nica o chorro de arena para formar una superficie adecuada. Aspire o sople el polvo con aire comprimido sin aceites. Frote mec\u00e1nicamente las placas base de metal para lograr un acabado met\u00e1lico brillante. El acero expuesto debe tratarse con chorro de arena y aspirarse para limpiarlo, si no es posible, retire la grasa de la superficie y use papel de lija o un cepillo de alambre para revelar el metal brillante continuo.<\/p>\n<p><strong>Mezclado &#8230;<\/strong> La resina y el endurecedor (contenidos en el cartucho doble) deben acondicionarse entre 18 y 29\u00a0\u00b0C (65 y 85 \u00b0F) en el momento de la aplicaci\u00f3n.\u00a0 Use el m\u00e9todo de hervidor doble o almacene el material en una sala tibia, antes de su aplicaci\u00f3n. Agite el cartucho vigorosamente por 60 segundos y luego deje el cartucho vertical por 60 segundos, dejando que suban las burbujas arriba.<\/p>\n<p><strong>M\u00c9TODO DE APLICACI\u00d3N<\/strong><\/p>\n<ol>\n<li>La temperatura del sustrato debe ser de 4 \u00b0C (40\u00a0\u00b0F) y creciente en el momento de la aplicaci\u00f3n.<\/li>\n<li>Revise que la boquilla mezcladora est\u00e1tica est\u00e9 sin obstrucciones.<\/li>\n<li>Retire la tapa de la punta.<\/li>\n<li>Retire el tap\u00f3n de la punta.<\/li>\n<li>Inserte el mezclador est\u00e1tico en la punta del cartucho. Deslice la tuerca de retenci\u00f3n (ubicada en la bolsa sellada) hacia abajo por el eje del mezclador est\u00e1tico.<\/li>\n<li>Apriete la tuerca de retenci\u00f3n en la punta del cartucho.<\/li>\n<li>Cargue en la herramienta dispensadora de cartucho doble est\u00e1ndar.<\/li>\n<li>Dispense y descarte aproximadamente una l\u00ednea de 73.2 mm (3 pulg.) de material hasta que se logre un color \u00e1mbar uniforme.<\/li>\n<li>Reinserte el tap\u00f3n de la punta y selle con la tapa de la punta para proteger el cartucho parcialmente usado.<\/li>\n<li>Siga todas las instrucciones antes de la aplicaci\u00f3n del cartucho parcialmente usado.<\/li>\n<\/ol>\n<p><strong>Inyecci\u00f3n de grietas \u2026 <\/strong>Se puede inyectar ep\u00f3xico en grietas finas que sean peque\u00f1as (ancho m\u00e1ximo de 3.2 mm [1\/8 de pulg.]).\u00a0 Selle la superficie de la grieta y fije los puertos de inyecci\u00f3n de REZI-WELD usando <a href=\"https:\/\/www.wrmeadows.com\/es\/rezi-weld-gel-paste-state-espanol\/\">REZI-WELD GEL PASTE STATE<\/a> o POLY-GRIP<sub>\u2122<\/sub> de W. R. MEADOWS.\u00a0 Deje pasar suficiente tiempo para que se endurezca la superficie antes de inyectar.\u00a0 Si se utiliza uno de los dos cartuchos, siempre use una pistola aplicadora de alta relaci\u00f3n que tenga una ventaja mec\u00e1nica con relaci\u00f3n de 35:1.<\/p>\n<p><strong>Alimentaci\u00f3n por gravedad \u2026<\/strong> Selle por debajo la losa elevada para rellenar si las grietas reflejan la profundidad completa.\u00a0 Vierta la mezcla ordenada debidamente mezclada y acondicionada de REZI-WELD LV STATE en la grieta con muesca en forma de V.\u00a0 Contin\u00fae la colocaci\u00f3n hasta rellenar totalmente.<\/p>\n<p><strong>Capa superior interior, antideslizante \u2026<\/strong> Aplique ep\u00f3xico mezclado a un promedio que no sobrepase 2.7 m<sup>2<\/sup>\/L\u00a0 (100 pies<sup>2<\/sup>\/gal.). Luego aplique una capa de arena o gravilla encima y deje curar el ep\u00f3xico.\u00a0 Sople o aspire el exceso de arena para eliminarlo. NOTA: NO DEBE USARSE REZI-WELD LV STATE COMO REVESTIMIENTO PARA PISOS TERMINADOS NI TRATAMIENTO PROTECTOR.<\/p>\n<p><strong>\u00c1ridos para morteros de ep\u00f3xico-resina \u2026<\/strong> Combine los \u00e1ridos limpios y secos con ep\u00f3xico reci\u00e9n mezclado a raz\u00f3n de una parte de ep\u00f3xico por 4 a 5 partes, por volumen, de \u00e1ridos calificados (sin superar seis partes de arena).\u00a0 El grosor de los parches no debe sobrepasar 50.5 mm (1.5 pulg.) por pasada.<\/p>\n<p><strong>Limpieza <\/strong>\u2026 Limpie las herramientas y el equipo inmediatamente con tolueno o xileno.\u00a0 Limpie el equipo alejado de las fuentes de inflamaci\u00f3n y evite respirar los vapores o permitir que el solvente con ep\u00f3xico entre en contacto con la piel.\u00a0 Si este material entra en contacto con la piel, l\u00e1vese totalmente con agua y jab\u00f3n, <u>no<\/u> solvente.<\/p>\n<p><strong>PRECAUCIONES<\/strong><br \/>\nNO LO DILUYA.\u00a0 Mezcle solamente unidades completas.\u00a0 No se recomienda usarlo cuando la temperatura del concreto ha estado bajo 4 \u00b0C (40 \u00b0F) durante las \u00faltimas 24 horas. No lo use para sellar grietas bajo presi\u00f3n hidrost\u00e1tica. No entibie el ep\u00f3xico sobre calor directo. No debe usarse REZI-WELD LV STATE como revestimiento exterior porque no resiste los rayos ultravioleta. No lo use cuando la temperatura del sustrato en el momento de la aplicaci\u00f3n est\u00e1 sobre 43 \u00b0C (110 \u00b0F).<\/p>\n<p><strong>PELIGROS DE SALUD<\/strong><br \/>\nEste ep\u00f3xico es corrosivo. Es necesario usar equipo protector personal. El ep\u00f3xico no utilizado generar\u00e1 calor excesivo, especialmente en grandes cantidades. El ep\u00f3xico no utilizado debe mezclarse con arena seca en el recipiente para ayudar a disminuir el calor. Consulte la Hoja de datos de seguridad del material para ver informaci\u00f3n completa sobre salud y seguridad.<\/p>\n<p><a href=\"https:\/\/www.wrmeadows.com\/es\/leed-guide\/\"><strong>INFORMACI\u00d3N LEED<\/strong><\/a><br \/>\nPuede ayudar a contribuir a los cr\u00e9ditos LEED:<\/p>\n<ul>\n<li>Cr\u00e9dito IEQ 4.1: Materiales con emisiones bajas: Adhesivos y selladores<\/li>\n<li>Cr\u00e9dito MR 2: Administraci\u00f3n del desecho de la construcci\u00f3n<\/li>\n<li>Cr\u00e9dito MR 5: Materiales regionales<\/li>\n<\/ul>\n<p><span>2013-09<\/span><br \/>\n<span><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-foot.jpg\" alt=\"\" width=\"671\" height=\"85\" align=\"BOTTOM\" border=\"0\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-footer.jpg\" alt=\"\" width=\"674\" height=\"220\" align=\"BOTTOM\" border=\"0\" \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REZI-WELD LV STATE es una resina inyectable estructural, de base ep\u00f3xica y viscosidad ultra-baja, de dos componentes, 100% s\u00f3lidos, que fragua r\u00e1pidamente. Es un sistema de resina ep\u00f3xica de ultrabaja viscosidad, m\u00f3dulo alto, sin solventes, bajo olor, alta resistencia, insensible a la humedad. <\/p>\n","protected":false},"author":1,"featured_media":15466,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"full-width-content","footnotes":""},"categories":[144,147,3],"tags":[],"class_list":["post-2344","post","type-post","status-publish","format-standard","has-post-thumbnail","category-anchoring-bonding-adhesives-es","category-grout-es","category-construction-products","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>REZI-WELD LV STATE (Espa\u00f1ol) - Adhesivo ep\u00f3xico inyectable de viscosidad ultra-baja - W. R. Meadows<\/title>\n<meta name=\"description\" content=\"REZI-WELD LV STATE es una resina inyectable estructural, de base ep\u00f3xica y viscosidad ultra-baja, de dos componentes, 100% s\u00f3lidos, que fragua r\u00e1pidamente. Es un sistema de resina ep\u00f3xica de ultrabaja viscosidad, m\u00f3dulo alto, sin solventes, bajo olor, alta resistencia, insensible a la humedad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REZI-WELD LV STATE (Espa\u00f1ol)\" \/>\n<meta property=\"og:description\" content=\"REZI-WELD LV STATE es una resina inyectable estructural, de base ep\u00f3xica y viscosidad ultra-baja, de dos componentes, 100% s\u00f3lidos, que fragua r\u00e1pidamente. Es un sistema de resina ep\u00f3xica de ultrabaja viscosidad, m\u00f3dulo alto, sin solventes, bajo olor, alta resistencia, insensible a la humedad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/\" \/>\n<meta property=\"og:site_name\" content=\"W. R. Meadows\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wrmeadows\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-01T14:47:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-10T16:23:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"W. R. MEADOWS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wrmeadows\" \/>\n<meta name=\"twitter:site\" content=\"@wrmeadows\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"W. R. MEADOWS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/\"},\"author\":{\"name\":\"W. R. MEADOWS\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/person\\\/0ffb3012c975c9703745930b937e0fa3\"},\"headline\":\"REZI-WELD LV STATE (Espa\u00f1ol)\",\"datePublished\":\"2012-03-01T14:47:23+00:00\",\"dateModified\":\"2020-02-10T16:23:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/\"},\"wordCount\":1440,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg\",\"articleSection\":[\"Anchoring &amp; Bonding\",\"Construction Grout\",\"Construction Products\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/\",\"name\":\"REZI-WELD LV STATE (Espa\u00f1ol) - Adhesivo ep\u00f3xico inyectable de viscosidad ultra-baja - W. R. Meadows\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg\",\"datePublished\":\"2012-03-01T14:47:23+00:00\",\"dateModified\":\"2020-02-10T16:23:19+00:00\",\"description\":\"REZI-WELD LV STATE es una resina inyectable estructural, de base ep\u00f3xica y viscosidad ultra-baja, de dos componentes, 100% s\u00f3lidos, que fragua r\u00e1pidamente. Es un sistema de resina ep\u00f3xica de ultrabaja viscosidad, m\u00f3dulo alto, sin solventes, bajo olor, alta resistencia, insensible a la humedad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg\",\"width\":550,\"height\":446},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/rezi-weld-lv-state-espanol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construction Products\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Restauraci\u00f3n de Concreto\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/concrete-restoration-es\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Construction Grout\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/concrete-restoration-es\\\/grout-es\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"REZI-WELD LV STATE (Espa\u00f1ol)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\",\"name\":\"W. R. Meadows\",\"description\":\"Concrete Construction Products Manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\",\"name\":\"W. R. Meadows\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/logo-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/logo-3.jpg\",\"width\":709,\"height\":709,\"caption\":\"W. R. Meadows\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wrmeadows\",\"https:\\\/\\\/x.com\\\/wrmeadows\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/w-r-meadows-inc\",\"https:\\\/\\\/www.youtube.com\\\/WrmeadowsTraining\",\"https:\\\/\\\/www.instagram.com\\\/wrmeadowsinc\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/person\\\/0ffb3012c975c9703745930b937e0fa3\",\"name\":\"W. R. MEADOWS\",\"description\":\"W. R. MEADOWS, INC. designs, manufactures, and markets high-quality building materials for today's construction professionals. Products are sold through an authorized distribution network. The family-owned and operated company focuses on product quality, exceptional service, and trusted integrity since its founding in 1926. About Us | Vapor Barriers | Air Barriers | Concrete Expansion Joints | All Construction Products\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"REZI-WELD LV STATE (Espa\u00f1ol) - Adhesivo ep\u00f3xico inyectable de viscosidad ultra-baja - W. R. Meadows","description":"REZI-WELD LV STATE es una resina inyectable estructural, de base ep\u00f3xica y viscosidad ultra-baja, de dos componentes, 100% s\u00f3lidos, que fragua r\u00e1pidamente. Es un sistema de resina ep\u00f3xica de ultrabaja viscosidad, m\u00f3dulo alto, sin solventes, bajo olor, alta resistencia, insensible a la humedad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/","og_locale":"en_US","og_type":"article","og_title":"REZI-WELD LV STATE (Espa\u00f1ol)","og_description":"REZI-WELD LV STATE es una resina inyectable estructural, de base ep\u00f3xica y viscosidad ultra-baja, de dos componentes, 100% s\u00f3lidos, que fragua r\u00e1pidamente. Es un sistema de resina ep\u00f3xica de ultrabaja viscosidad, m\u00f3dulo alto, sin solventes, bajo olor, alta resistencia, insensible a la humedad.","og_url":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/","og_site_name":"W. R. Meadows","article_publisher":"https:\/\/www.facebook.com\/wrmeadows","article_published_time":"2012-03-01T14:47:23+00:00","article_modified_time":"2020-02-10T16:23:19+00:00","og_image":[{"width":550,"height":446,"url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg","type":"image\/jpeg"}],"author":"W. R. MEADOWS","twitter_card":"summary_large_image","twitter_creator":"@wrmeadows","twitter_site":"@wrmeadows","twitter_misc":{"Escrito por":"W. R. MEADOWS","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/#article","isPartOf":{"@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/"},"author":{"name":"W. R. MEADOWS","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/person\/0ffb3012c975c9703745930b937e0fa3"},"headline":"REZI-WELD LV STATE (Espa\u00f1ol)","datePublished":"2012-03-01T14:47:23+00:00","dateModified":"2020-02-10T16:23:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/"},"wordCount":1440,"publisher":{"@id":"https:\/\/www.wrmeadows.com\/es\/#organization"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg","articleSection":["Anchoring &amp; Bonding","Construction Grout","Construction Products"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/","url":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/","name":"REZI-WELD LV STATE (Espa\u00f1ol) - Adhesivo ep\u00f3xico inyectable de viscosidad ultra-baja - W. R. Meadows","isPartOf":{"@id":"https:\/\/www.wrmeadows.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/#primaryimage"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg","datePublished":"2012-03-01T14:47:23+00:00","dateModified":"2020-02-10T16:23:19+00:00","description":"REZI-WELD LV STATE es una resina inyectable estructural, de base ep\u00f3xica y viscosidad ultra-baja, de dos componentes, 100% s\u00f3lidos, que fragua r\u00e1pidamente. Es un sistema de resina ep\u00f3xica de ultrabaja viscosidad, m\u00f3dulo alto, sin solventes, bajo olor, alta resistencia, insensible a la humedad.","breadcrumb":{"@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/#primaryimage","url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg","contentUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg","width":550,"height":446},{"@type":"BreadcrumbList","@id":"https:\/\/www.wrmeadows.com\/es\/rezi-weld-lv-state-espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wrmeadows.com\/es\/"},{"@type":"ListItem","position":2,"name":"Construction Products","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/"},{"@type":"ListItem","position":3,"name":"Restauraci\u00f3n de Concreto","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/concrete-restoration-es\/"},{"@type":"ListItem","position":4,"name":"Construction Grout","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/concrete-restoration-es\/grout-es\/"},{"@type":"ListItem","position":5,"name":"REZI-WELD LV STATE (Espa\u00f1ol)"}]},{"@type":"WebSite","@id":"https:\/\/www.wrmeadows.com\/es\/#website","url":"https:\/\/www.wrmeadows.com\/es\/","name":"W. R. Meadows","description":"Concrete Construction Products Manufacturer","publisher":{"@id":"https:\/\/www.wrmeadows.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wrmeadows.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.wrmeadows.com\/es\/#organization","name":"W. R. Meadows","url":"https:\/\/www.wrmeadows.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/logo-3.jpg","contentUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/logo-3.jpg","width":709,"height":709,"caption":"W. R. Meadows"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wrmeadows","https:\/\/x.com\/wrmeadows","https:\/\/www.linkedin.com\/company\/w-r-meadows-inc","https:\/\/www.youtube.com\/WrmeadowsTraining","https:\/\/www.instagram.com\/wrmeadowsinc\/"]},{"@type":"Person","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/person\/0ffb3012c975c9703745930b937e0fa3","name":"W. R. MEADOWS","description":"W. R. MEADOWS, INC. designs, manufactures, and markets high-quality building materials for today's construction professionals. Products are sold through an authorized distribution network. The family-owned and operated company focuses on product quality, exceptional service, and trusted integrity since its founding in 1926. About Us | Vapor Barriers | Air Barriers | Concrete Expansion Joints | All Construction Products"}]}},"jetpack_featured_media_url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/ultra-low-viscosity-injection-epoxy-rezi-weld-lv-state.jpg","_links":{"self":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts\/2344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/comments?post=2344"}],"version-history":[{"count":0,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts\/2344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/media\/15466"}],"wp:attachment":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/media?parent=2344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/categories?post=2344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/tags?post=2344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}