{"id":2426,"date":"2012-03-01T10:24:58","date_gmt":"2012-03-01T16:24:58","guid":{"rendered":"http:\/\/test7.wrmeadows.com\/?p=2426"},"modified":"2019-11-21T09:37:33","modified_gmt":"2019-11-21T15:37:33","slug":"deck-o-shield-espanol","status":"publish","type":"post","link":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/","title":{"rendered":"DECK-O-SHIELD (Espa\u00f1ol)"},"content":{"rendered":"<p><a name=\"ds\"><\/a><\/p>\n<h3 class=\"section\">Hoja de datos del producto<\/h3>\n<h3><a href=\"https:\/\/www.wrmeadows.com\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Datos de Producto, W. R. MEADOWS\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-dosblue.png\" width=\"680\" height=\"107\" align=\"bottom\" border=\"0\" \/><\/a><\/h3>\n<table width=\"680\" border=\"0\" cellspacing=\"2\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td width=\"22%\"><strong><span style=\"font-family: Arial,Helvetica,sans-serif;\"><a href=\"https:\/\/www.wrmeadows.com\/sp\/#div32\">07 19 00<\/a><\/span><\/strong><\/td>\n<td width=\"30%\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><strong>795 &#8211; <em><span><a href=\"https:\/\/www.wrmeadows.com\/espanol\/data\/795-esp.pdf\">versi\u00f3n impresa<\/a><\/span><\/em><\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>DECK-O-SHIELD<\/strong><br \/>\n<strong>Sellador para concreto, cascadas y piedra natural<\/strong><\/p>\n<p><span style=\"font-family: Arial,Helvetica,sans-serif;\"><strong>DESCRIPCI\u00d3N<\/strong><\/span><br \/>\nDECK-O-SHIELD es un sellador\/repelente de agua listo para usar, a base de agua para superficies de piedra natural, concreto y mamposter\u00eda. DECK-O-SHIELD est\u00e1 dise\u00f1ado para usarse como sellador\/repelente de agua en cascadas o alrededor o dentro de piscinas; el producto limita la penetraci\u00f3n de agua dentro de superficies estructuralmente s\u00f3lidas, sin grietas. Tambi\u00e9n puede usarse el producto como sellador\/repelente de agua para patios de piedra natural, senderos o terrazas; virtualmente cualquier \u00e1rea situada cerca o alrededor de piscinas. Las superficies tratadas con DECK-O-SHIELD inhiben la penetraci\u00f3n de sales, reduciendo el &#8220;blanqueado&#8221; o las manchas.<\/p>\n<p><strong>USOS<\/strong><br \/>\nDECK-O-SHIELD impermeabiliza y protege pr\u00e1cticamente toda cascada, terraza, porche, patio y sendero alrededor de piscinas, incluso las siguientes superficies: piedra natural, juntas de mortero, concreto, ladrillo, bloques de concreto y estuco.<\/p>\n<p>Otra ventaja que aporta DECK-O-SHIELD es que el producto no altera el color ni el tinte de la superficie despu\u00e9s de aplicarlo. No hay necesidad de preocuparse al aplicar DECK-O-SHIELD, porque el producto no tiene efectos perjudiciales sobre el aspecto de la superficie despu\u00e9s de la aplicaci\u00f3n.<\/p>\n<p><strong>CARACTER\u00cdSTICAS\/VENTAJAS<\/strong><\/p>\n<ul>\n<li>Respirable &#8211; permite que se evapore la humedad en el concreto curado.<\/li>\n<li>DECK-O-SHIELD es un material que no forma pel\u00edcula &#8211; penetra la superficie para formar una barrera integral contra la penetraci\u00f3n de humedad.<\/li>\n<li>Es transparente y no mancha.<\/li>\n<li>La apariencia de la superficie despu\u00e9s de aplicar y dejar secar completamente se ve pr\u00e1cticamente inalterada.<\/li>\n<li>Reduce las part\u00edculas de suciedad atrapadas y otros contaminantes que causan decoloraci\u00f3n; inhibe las manchas.<\/li>\n<li>Protege contra la eflorescencia y las manchas de corrosi\u00f3n.<\/li>\n<li>Ayuda a resistir las manchas de derrames.<\/li>\n<li>Protege contra las manchas de sal y el &#8220;blanqueado&#8221; que provoca la sal en el agua.<\/li>\n<li>A base de agua, cumple con la norma de VOC.<\/li>\n<li>Un componente.<\/li>\n<li>Aceptado por el Depto. de Agricultura de los EE.UU. [USDA]<\/li>\n<\/ul>\n<p><b>EMPAQUE<\/b><br \/>\nUnidades de 3.79 Litros (1 gal\u00f3n)<br \/>\nBaldes de 18.93 Litros (5 galones)<\/p>\n<p><b>COBERTURA*<\/b><br \/>\nPiedra natural**  &nbsp; &nbsp;   1.8 \u2013 4.2 m\u00b2\/L  (75 \u2013 175 pies<sup>2<\/sup>\/gal.)<br \/>\nConcreto  &nbsp; &nbsp;    2.4 \u2013 4.2 m\u00b2\/L (100 \u2013 175 pies<sup>2<\/sup>\/gal.)<br \/>\nMamposter\u00eda   &nbsp; &nbsp;   2.4 \u2013 4.2 m\u00b2\/L (100 \u2013 175 pies<sup>2<\/sup>\/gal.)<br \/>\nSuperficies de estuc  &nbsp; &nbsp;   1.4 \u2013 2.4 m\u00b2\/L (60 \u2013 100 pies<sup>2<\/sup>\/gal.)<br \/>\nBloque de concreto**  &nbsp; &nbsp;   1.2 \u2013 2.4 m\u00b2\/L (50 \u2013 100 pies<sup>2<\/sup>\/gal)**<b><\/b><\/p>\n<p>*Siempre aplique un \u00e1rea de prueba para determinar los \u00edndices reales de cobertura. La cobertura puede variar en gran medida debido a la porosidad del sustrato.<\/p>\n<p>**Debido a la porosidad, ciertas aplicaciones en piedra y bloques pueden necesitar un aumento considerable de los \u00edndices de cobertura \u2013 puede tener que hacer aplicaciones adicionales.<\/p>\n<p><b>DURACI\u00d3N EN ALMACENAMIENTO<\/b><b><\/b><br \/>\nCuando se guarda en interiores y en su envase original, sin abrir, a temperaturas entre 4 &#8211; 32\u00b0 C (40 &#8211; 90\u00b0 F), la duraci\u00f3n en almacenaje es de un m\u00ednimo de dos a\u00f1os desde la fecha de fabricaci\u00f3n.<\/p>\n<p><b>ESPECIFICACIONES<\/b><\/p>\n<ul>\n<li>&bull; Cumple con todos los requisitos VOC m\u00e1ximos permitidos federales, estatales y locales actuales, incluyendo U.S. EPA, LADCO, SCAQMD y OTC.<\/li>\n<\/ul>\n<p><b>DATOS T\u00c9CNICOS<\/b><b><br \/>\n<\/b>Seco al tacto            1 \u2013 2 horas (t\u00edpicamente)<br \/>\nPermitir 12 \u2013 14 horas entre                                                                                    capaas para varias aplicaciones<br \/>\nColor                       Emulsi\u00f3n de color blanco lechoso<\/p>\n<p><strong>APLICACI\u00d3N<\/strong><br \/>\n<b>Preparaci\u00f3n de la superficie \u2026 <\/b>Proteja personas, veh\u00edculos, bienes, plantas y toda superficie que no sea de mamposter\u00eda contra productos, salpicaduras, residuos y acumulaciones provocadas por el viento. Limpie completamente la superficie. Aunque puede aplicarse DECK-O-SHIELD en superficies ligeramente h\u00famedas, se logra el \u00f3ptimo rendimiento sobre una superficie limpia,  totalmente seca y absorbente. El exceso de humedad inhibe la penetraci\u00f3n, reduciendo la vida \u00fatil y el rendimiento del tratamiento. Siempre pruebe la compatibilidad. Las superficies deben ser estructuralmente s\u00f3lidas, estar limpias y sin suciedad, eflorescencia y manchas.<\/p>\n<p><strong>Temperaturas de la superficie y del aire<\/strong> \u2026 La temperatura \u00f3ptima de la superficie y del aire es entre 4\u00b0 y 35\u00b0 C (40\u00b0 y 95\u00b0 F) durante la aplicaci\u00f3n y ocho horas despu\u00e9s. Si existen condiciones de congelaci\u00f3n antes de la aplicaci\u00f3n, deje que se descongele la superficie a tratar. El portador de agua de DECK-O-SHIELD puede congelarse a bajas temperaturas o evaporarse a altas temperaturas. Ambas condiciones perjudican la penetraci\u00f3n y los resultados.<\/p>\n<p><strong>Equipo<\/strong> \u2026 Aplique con brocha, rodillo o rociador de baja presi\u00f3n (&lt;50 psi), dependiendo de la textura de la superficie, \u00e1rea, etc. Se recomiendan puntas en abanico para los rociadores. Se aconseja usar un rociador Chapin 1949 con boquilla 1-5915.<\/p>\n<p><strong>Aplicaci\u00f3n de prueba<\/strong> \u2026 Siempre realice una aplicaci\u00f3n de prueba en cada tipo de superficie antes de aplicar a escala completa para determinar la idoneidad y apariencia final. Pruebe usando las instrucciones de aplicaci\u00f3n recomendadas. Deje que el \u00e1rea se seque por completo antes de inspeccionar.<\/p>\n<p><strong>Instrucciones para la aplicaci\u00f3n vertical<\/strong> \u2026 Para obtener \u00f3ptimos resultados, aplique sobre una superficies visiblemente seca y absorbente.<\/p>\n<p><strong>Rociador<\/strong> \u2026 Sature desde abajo hacia arriba, creando una pasada de 10 a 20 cm (4 a 8 pulgadas) bajo el punto de contacto del rociado. Deje que penetre la primera aplicaci\u00f3n unos 5 a 10 minutos. Vuelva a saturar mientras la superficie parezca todav\u00eda h\u00fameda. Se necesitar\u00e1 menos producto para la segunda aplicaci\u00f3n.<\/p>\n<p><strong>Brocha o rodillo<\/strong> \u2026 Sature uniformemente. Deje penetrar unos 5 a 10 minutos. Elimine con la brocha las pasadas y gotas que no penetren.<\/p>\n<p><strong>Instrucciones de aplicaci\u00f3n para superficies densas<\/strong> \u2026 Aplique una sola capa. Use suficiente para mojar completamente la superficie sin producir goteos, pozas ni escurrimientos. NO APLIQUE EN EXCESO.<\/p>\n<p><strong>Instrucciones de aplicaci\u00f3n horizontal<\/strong> \u2026 Sature en una sola aplicaci\u00f3n. Use suficiente como para mantener la superficie mojada unos 2 a 3 minutos antes de la penetraci\u00f3n. Barra toda poza o gotas hasta que se absorban.<\/p>\n<p>Nota: Las condiciones con mucho calor y viento evaporan el portador de agua, reduciendo la penetraci\u00f3n y el rendimiento. En d\u00edas calurosos y de mucho viento, aplique temprano en el d\u00eda y a la sombra, si es posible. Las superficies tratadas quedan secas al tacto en 1 a 2 horas. Proteja las superficies contra la lluvia durante seis horas despu\u00e9s del tratamiento. Muchas superficies necesitan varios d\u00edas para desarrollar \u00f3ptimas cualidades repelentes de agua.<\/p>\n<p><strong>Capas adicionales<\/strong> \u2026 Una vez que la superficie tratada haya recibido la cantidad \u00f3ptima de DECK-O-SHIELD, toda capa adicional producir\u00e1 gotas sobre la superficie. Deje de aplicar una vez que ocurra esto. Puede aplicarse la serie de productos CS-309<sub>\u2122<\/sub>, EXPO-GLOSS<sub>\u00ae<\/sub>, DECRA-SEAL<sub>\u2122<\/sub>, TIAH<sub><sub>\u00ae<\/sub> <\/sub>y VOCOMP<sub>\u00ae<\/sub> de W. R. MEADOWS sobre una superficie tratada con DECK-O-SHIELD. La barrera resultante causar\u00e1 gotas de agua y, dependiendo del producto usado, tambi\u00e9n tendr\u00e1 una apariencia superficial brillante. Debe efectuarse la aplicaci\u00f3n inicial de DECK-O-SHIELD correctamente y con la tasa de aplicaci\u00f3n recomendada.<\/p>\n<p><strong>Limpieza<\/strong> \u2026 Limpie inmediatamente las herramientas, el equipo y el exceso rociado con agua tibia y jab\u00f3n.<\/p>\n<p><b>PRECAUCIONES<\/b><br \/>\nNO LO DILUYA NI ALTERE. MEZCLE TOTALMENTE ANTES DEL USO. NO LO CONGELE. DECK-O-SHIELD es un repelente de agua, no impermeabiliza ni es una barrera contra el vapor. No oculta las manchas existentes en la superficie. No debe aplicarse DECK-O-SHIELD en las superficies que van a recibir calafateos o selladores. La aplicaci\u00f3n sobre selladores elastom\u00e9ricos totalmente curados com\u00fanmente no afecta al sellador. No se debe aplicar a superficies con temperaturas de &lt;4.4\u00b0 C (&lt;40\u00b0 F) o &gt;35\u00b0 C (&gt;95\u00b0 F). Evite derrames o rociar en exceso sobre fuentes de agua cercanas. Puede  ocurrir el oscurecimiento pasajero de algunos sustratos. Aplique una prueba en un \u00e1rea peque\u00f1a antes de realizar la aplicaci\u00f3n a escala completa. Consulte la Hoja de datos de seguridad del material para ver informaci\u00f3n completa sobre salud y seguridad.<\/p>\n<p><b>INFORMACI\u00d3N LEED<\/b><b><\/b><br \/>\nPuede ayudar a contribuir a los cr\u00e9ditos LEED:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.wrmeadows.com\/leed-guide\/#ieq\">Cr\u00e9dito IEQ 3.1<\/a>: Plan de administraci\u00f3n de calidad de aire interior de construcci\u00f3n: Durante la construcci\u00f3n<\/li>\n<li>Cr\u00e9dito IEQ 4.2: Materiales con baja emisi\u00f3n \u2013 Pinturas y revestimientos<\/li>\n<li>Cr\u00e9dito IEQ 4.3: Materiales con baja emisi\u00f3n \u2013 Sistemas de pisos<\/li>\n<li><a href=\"https:\/\/www.wrmeadows.com\/leed-guide\/#mr\">Cr\u00e9dito MR 2<\/a>: Administraci\u00f3n del desecho de la construcci\u00f3n<\/li>\n<li>Cr\u00e9dito MR 5: Materiales regionales<\/li>\n<\/ul>\n<p><strong>Para ver la hoja de datos de seguridad, mayor informaci\u00f3n LEED y MSDS m\u00e1s recientes, visite <a href=\"http:\/\/www.deckoseal.com\/\">www.deckoseal.com<\/a>.<\/strong><\/p>\n<p><a href=\"https:\/\/www.wrmeadows.com\/greenspec-products\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Green Spec\" src=\"https:\/\/www.wrmeadows.com\/images\/greenspec.gif\" width=\"150\" height=\"61\" align=\"bottom\" border=\"0\" \/><\/a><\/p>\n<p><span style=\"font-family: Arial;\">2013-03<\/span><\/p>\n<p><span style=\"font-family: Arial;\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-foot.jpg\" width=\"671\" height=\"85\" align=\"bottom\" border=\"0\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-footer.jpg\" width=\"674\" height=\"220\" align=\"bottom\" border=\"0\" \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECK-O-SHIELD es un sellador\/repelente de agua listo para usar, a base de agua para superficies de piedra natural, concreto y mamposter\u00eda. DECK-O-SHIELD est\u00e1 dise\u00f1ado para usarse como sellador\/repelente de agua en cascadas o alrededor o dentro de piscinas; el producto limita la penetraci\u00f3n de agua dentro de superficies estructuralmente s\u00f3lidas, sin grietas.<\/p>\n","protected":false},"author":1,"featured_media":19270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"full-width-content","footnotes":""},"categories":[15656,3],"tags":[],"class_list":["post-2426","post","type-post","status-publish","format-standard","has-post-thumbnail","category-concrete-sealing-compounds-es","category-construction-products","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>DECK-O-SHIELD (Espa\u00f1ol)  - W. R. Meadows<\/title>\n<meta name=\"description\" content=\"DECK-O-SHIELD es un sellador\/repelente de agua listo para usar, a base de agua para superficies de piedra natural, concreto y mamposter\u00eda. DECK-O-SHIELD est\u00e1 dise\u00f1ado para usarse como sellador\/repelente de agua en cascadas o alrededor o dentro de piscinas; el producto limita la penetraci\u00f3n de agua dentro de superficies estructuralmente s\u00f3lidas, sin grietas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DECK-O-SHIELD (Espa\u00f1ol)\" \/>\n<meta property=\"og:description\" content=\"DECK-O-SHIELD es un sellador\/repelente de agua listo para usar, a base de agua para superficies de piedra natural, concreto y mamposter\u00eda. DECK-O-SHIELD est\u00e1 dise\u00f1ado para usarse como sellador\/repelente de agua en cascadas o alrededor o dentro de piscinas; el producto limita la penetraci\u00f3n de agua dentro de superficies estructuralmente s\u00f3lidas, sin grietas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/\" \/>\n<meta property=\"og:site_name\" content=\"W. R. Meadows\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wrmeadows\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-01T16:24:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-21T15:37:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/Deck-O-Shield-Concrete-Deck-Sealer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1215\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"W. R. MEADOWS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wrmeadows\" \/>\n<meta name=\"twitter:site\" content=\"@wrmeadows\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"W. R. MEADOWS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/\"},\"author\":{\"name\":\"W. R. MEADOWS\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/person\\\/0ffb3012c975c9703745930b937e0fa3\"},\"headline\":\"DECK-O-SHIELD (Espa\u00f1ol)\",\"datePublished\":\"2012-03-01T16:24:58+00:00\",\"dateModified\":\"2019-11-21T15:37:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/\"},\"wordCount\":1359,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/Deck-O-Shield-Concrete-Deck-Sealer.jpg\",\"articleSection\":[\"Concrete Sealing Compounds\",\"Construction Products\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/\",\"name\":\"DECK-O-SHIELD (Espa\u00f1ol)  - W. R. Meadows\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/Deck-O-Shield-Concrete-Deck-Sealer.jpg\",\"datePublished\":\"2012-03-01T16:24:58+00:00\",\"dateModified\":\"2019-11-21T15:37:33+00:00\",\"description\":\"DECK-O-SHIELD es un sellador\\\/repelente de agua listo para usar, a base de agua para superficies de piedra natural, concreto y mamposter\u00eda. DECK-O-SHIELD est\u00e1 dise\u00f1ado para usarse como sellador\\\/repelente de agua en cascadas o alrededor o dentro de piscinas; el producto limita la penetraci\u00f3n de agua dentro de superficies estructuralmente s\u00f3lidas, sin grietas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/Deck-O-Shield-Concrete-Deck-Sealer.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/Deck-O-Shield-Concrete-Deck-Sealer.jpg\",\"width\":1800,\"height\":1215},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/deck-o-shield-espanol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construction Products\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Construction Liquids\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/construction-liquids-es\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Concrete Sealing Compounds\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/construction-liquids-es\\\/concrete-sealing-compounds-es\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"DECK-O-SHIELD (Espa\u00f1ol)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\",\"name\":\"W. R. Meadows\",\"description\":\"Concrete Construction Products Manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\",\"name\":\"W. R. Meadows\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/logo-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/logo-3.jpg\",\"width\":709,\"height\":709,\"caption\":\"W. R. Meadows\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wrmeadows\",\"https:\\\/\\\/x.com\\\/wrmeadows\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/w-r-meadows-inc\",\"https:\\\/\\\/www.youtube.com\\\/WrmeadowsTraining\",\"https:\\\/\\\/www.instagram.com\\\/wrmeadowsinc\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/person\\\/0ffb3012c975c9703745930b937e0fa3\",\"name\":\"W. R. MEADOWS\",\"description\":\"W. R. MEADOWS, INC. designs, manufactures, and markets high-quality building materials for today's construction professionals. Products are sold through an authorized distribution network. The family-owned and operated company focuses on product quality, exceptional service, and trusted integrity since its founding in 1926. About Us | Vapor Barriers | Air Barriers | Concrete Expansion Joints | All Construction Products\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DECK-O-SHIELD (Espa\u00f1ol)  - W. R. Meadows","description":"DECK-O-SHIELD es un sellador\/repelente de agua listo para usar, a base de agua para superficies de piedra natural, concreto y mamposter\u00eda. DECK-O-SHIELD est\u00e1 dise\u00f1ado para usarse como sellador\/repelente de agua en cascadas o alrededor o dentro de piscinas; el producto limita la penetraci\u00f3n de agua dentro de superficies estructuralmente s\u00f3lidas, sin grietas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/","og_locale":"en_US","og_type":"article","og_title":"DECK-O-SHIELD (Espa\u00f1ol)","og_description":"DECK-O-SHIELD es un sellador\/repelente de agua listo para usar, a base de agua para superficies de piedra natural, concreto y mamposter\u00eda. DECK-O-SHIELD est\u00e1 dise\u00f1ado para usarse como sellador\/repelente de agua en cascadas o alrededor o dentro de piscinas; el producto limita la penetraci\u00f3n de agua dentro de superficies estructuralmente s\u00f3lidas, sin grietas.","og_url":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/","og_site_name":"W. R. Meadows","article_publisher":"https:\/\/www.facebook.com\/wrmeadows","article_published_time":"2012-03-01T16:24:58+00:00","article_modified_time":"2019-11-21T15:37:33+00:00","og_image":[{"width":1800,"height":1215,"url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/Deck-O-Shield-Concrete-Deck-Sealer.jpg","type":"image\/jpeg"}],"author":"W. R. MEADOWS","twitter_card":"summary_large_image","twitter_creator":"@wrmeadows","twitter_site":"@wrmeadows","twitter_misc":{"Escrito por":"W. R. MEADOWS","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/#article","isPartOf":{"@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/"},"author":{"name":"W. R. MEADOWS","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/person\/0ffb3012c975c9703745930b937e0fa3"},"headline":"DECK-O-SHIELD (Espa\u00f1ol)","datePublished":"2012-03-01T16:24:58+00:00","dateModified":"2019-11-21T15:37:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/"},"wordCount":1359,"publisher":{"@id":"https:\/\/www.wrmeadows.com\/es\/#organization"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/Deck-O-Shield-Concrete-Deck-Sealer.jpg","articleSection":["Concrete Sealing Compounds","Construction Products"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/","url":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/","name":"DECK-O-SHIELD (Espa\u00f1ol)  - W. R. Meadows","isPartOf":{"@id":"https:\/\/www.wrmeadows.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/#primaryimage"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/Deck-O-Shield-Concrete-Deck-Sealer.jpg","datePublished":"2012-03-01T16:24:58+00:00","dateModified":"2019-11-21T15:37:33+00:00","description":"DECK-O-SHIELD es un sellador\/repelente de agua listo para usar, a base de agua para superficies de piedra natural, concreto y mamposter\u00eda. DECK-O-SHIELD est\u00e1 dise\u00f1ado para usarse como sellador\/repelente de agua en cascadas o alrededor o dentro de piscinas; el producto limita la penetraci\u00f3n de agua dentro de superficies estructuralmente s\u00f3lidas, sin grietas.","breadcrumb":{"@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/#primaryimage","url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/Deck-O-Shield-Concrete-Deck-Sealer.jpg","contentUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/Deck-O-Shield-Concrete-Deck-Sealer.jpg","width":1800,"height":1215},{"@type":"BreadcrumbList","@id":"https:\/\/www.wrmeadows.com\/es\/deck-o-shield-espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wrmeadows.com\/es\/"},{"@type":"ListItem","position":2,"name":"Construction Products","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/"},{"@type":"ListItem","position":3,"name":"Construction Liquids","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/construction-liquids-es\/"},{"@type":"ListItem","position":4,"name":"Concrete Sealing Compounds","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/construction-liquids-es\/concrete-sealing-compounds-es\/"},{"@type":"ListItem","position":5,"name":"DECK-O-SHIELD (Espa\u00f1ol)"}]},{"@type":"WebSite","@id":"https:\/\/www.wrmeadows.com\/es\/#website","url":"https:\/\/www.wrmeadows.com\/es\/","name":"W. R. Meadows","description":"Concrete Construction Products Manufacturer","publisher":{"@id":"https:\/\/www.wrmeadows.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wrmeadows.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.wrmeadows.com\/es\/#organization","name":"W. R. Meadows","url":"https:\/\/www.wrmeadows.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/logo-3.jpg","contentUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/logo-3.jpg","width":709,"height":709,"caption":"W. R. Meadows"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wrmeadows","https:\/\/x.com\/wrmeadows","https:\/\/www.linkedin.com\/company\/w-r-meadows-inc","https:\/\/www.youtube.com\/WrmeadowsTraining","https:\/\/www.instagram.com\/wrmeadowsinc\/"]},{"@type":"Person","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/person\/0ffb3012c975c9703745930b937e0fa3","name":"W. R. MEADOWS","description":"W. R. MEADOWS, INC. designs, manufactures, and markets high-quality building materials for today's construction professionals. Products are sold through an authorized distribution network. The family-owned and operated company focuses on product quality, exceptional service, and trusted integrity since its founding in 1926. About Us | Vapor Barriers | Air Barriers | Concrete Expansion Joints | All Construction Products"}]}},"jetpack_featured_media_url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/Deck-O-Shield-Concrete-Deck-Sealer.jpg","_links":{"self":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts\/2426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/comments?post=2426"}],"version-history":[{"count":0,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts\/2426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/media\/19270"}],"wp:attachment":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/media?parent=2426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/categories?post=2426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/tags?post=2426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}