{"id":49463,"date":"2021-02-25T15:17:59","date_gmt":"2021-02-25T21:17:59","guid":{"rendered":"https:\/\/www.wrmeadows.com\/?p=49463"},"modified":"2024-01-16T09:54:52","modified_gmt":"2024-01-16T15:54:52","slug":"form-oil-espanol","status":"publish","type":"post","link":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/","title":{"rendered":"FORM OIL (Espa\u00f1ol)"},"content":{"rendered":"<p><a name=\"ds\"><\/a><\/p>\n<h3 class=\"section\">Hoja de datos del producto<\/h3>\n<p><a href=\"https:\/\/www.wrmeadows.com\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-hdgreen.jpg\" alt=\"Datos de Producto, W. R. MEADOWS\" width=\"679\" height=\"151\" align=\"BOTTOM\" border=\"0\" \/><\/a><\/p>\n<table border=\"0\" width=\"100%\" cellspacing=\"2\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td width=\"30%\"><strong>365 &#8211; <em><a href=\"https:\/\/www.wrmeadows.com\/espanol\/data\/Form-Oil-365-esp.pdf\">versi\u00f3n impresa<\/a><\/em><\/strong><\/td>\n<td width=\"29%\"><strong><a href=\"https:\/\/www.wrmeadows.com\/sp\/#div3\">03 11 00<\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>FORM OIL<\/strong><br \/>\n<strong>Agente liberador de forma conforme a la norma VOC<\/strong><\/p>\n<p><strong>DESCRIPCI\u00d3N<\/strong><br \/>\nFORM OIL est\u00e1 compuesto por un ingrediente qu\u00edmicamente inerte y de alto peso molecular y est\u00e1 orientado a prevenir la uni\u00f3n del concreto a la forma. El agente liberador de forma FORM OIL, cuando se aplica de manera adecuada, es una manera econ\u00f3mica de reducir sustancialmente la posible formaci\u00f3n de agujeros diminutos.<\/p>\n<p><strong>USOS<\/strong><br \/>\nSe puede usar FORM OIL en formas como madera, acero, aluminio, reforzadas con fibra de vidrio, todos los tipos de madera laminada (lo que incluye la previamente aceitada, superpuesta, LDO, NDO, HDO), con revestimiento ep\u00f3xico y de uretano, as\u00ed como tubos de fibra. FORM OIL aumenta la vida \u00fatil de las formas de madera ya que penetra en la madera para dar resistencia al agua y evitar el deterioro. Tambi\u00e9n reduce los requisitos de mantenimiento en las formas de metal mediante el desarrollo de una pel\u00edcula resistente a la corrosi\u00f3n que deja la forma met\u00e1lica pr\u00e1cticamente autolimpiante y sin corrosi\u00f3n.<\/p>\n<p>FORM OIL puede aplicarse a formas de tubo de fibra, aunque puedan estar previamente revestidas. Los tubos se decapan m\u00e1s f\u00e1cilmente, incluso 60 a 90 d\u00edas despu\u00e9s. Si los tubos se decapan dentro de 5 a 10 d\u00edas, se facilita en gran medida frotar con las manos cuando los tubos est\u00e1n revestidos con FORM OIL.<\/p>\n<p>FORM OIL tambi\u00e9n reduce el tiempo de limpieza porque minimiza la acumulaci\u00f3n de concreto. Los equipos como pavimentadoras, camiones, mezcladoras, dispersadoras- terminadoras, carretillas, canaletas y otros tipos deben rociarse diariamente con FORM OIL para facilitar la limpieza y prevenir la corrosi\u00f3n.<\/p>\n<p>FORM OIL puede aplicarse en formas para concreto previamente tensado y moldeado para producir un molde mejor y m\u00e1s limpio. Cuando se aplica de manera adecuada, FORM OIL no mancha ni descolora el concreto y reducir\u00e1 sustancialmente la formaci\u00f3n de agujeros diminutos.<\/p>\n<p><strong>EMPAQUE<\/strong><br \/>\nLatas de 3.79\u00a0litros (1\u00a0gal\u00f3n) (4 por caja)<br \/>\nCubetas de 18.93\u00a0litros (5\u00a0galones)<br \/>\nTambores de 208.2\u00a0litros (55\u00a0galones)<br \/>\nContenedor de 1,041\u00a0litros (275\u00a0galones)<\/p>\n<p><strong>COBERTURA<\/strong><br \/>\n55.7 a 139.3 m<sup>2<\/sup>\/L (600 a 1,500 pies<sup>2<\/sup>\/gal.) La cobertura var\u00eda debido a la textura, porosidad y el estado de las formas.<\/p>\n<p><strong>DURACI\u00d3N EN ALMACENAMIENTO<\/strong><br \/>\nCuando se guarda en interiores y en su envase original, sin abrir, a temperaturas entre 4 y 32\u00a0\u00b0C (40 a 90\u00a0\u00b0F), se obtiene el rendimiento \u00f3ptimo y el mejor uso dentro de dos a\u00f1os desde la fecha de fabricaci\u00f3n.<\/p>\n<p><strong>ESPECIFICACIONES<\/strong><\/p>\n<ul>\n<li>Cumple con todos los actuales requerimientos de VOC m\u00e1ximo admisible a nivel federal, estatal y local, los que incluyen CARB, condado de Maricopa en Arizona, Departamento de Calidad Ambiental de Utah, la EPA de EE.\u00a0UU. y SCAQMD.<\/li>\n<\/ul>\n<p><strong>DATOS T\u00c9CNICOS<\/strong><br \/>\nContenido de compuestos org\u00e1nicos vol\u00e1tiles (VOC): 82\u00a0g\/L<\/p>\n<p><strong>APLICACI\u00d3N<\/strong><br \/>\n<strong>Preparaci\u00f3n de la superficie&#8230; <\/strong>Las superficies de las formas deben limpiarse totalmente antes de la aplicaci\u00f3n. Se debe eliminar todo tipo de corrosi\u00f3n y sarro de acuerdo con las buenas pr\u00e1cticas de concreto. Es indispensable, cuando se usan nuevas formas de madera de todo tipo (madera simple, madera laminada, corte en bruto, etc.) que se aplique y vuelva a aplicar FORM OIL hasta que se sature por completo antes del primer uso.<\/p>\n<p><strong>M\u00e9todo de aplicaci\u00f3n\u2026<\/strong> Rociar es el m\u00e9todo ideal de aplicaci\u00f3n. Use un rociador industrial, como Chapin 1949, con una boquilla rociadora que emita un flujo de 0.379\u00a0LPM (0.1\u00a0GPM). FORM OIL se puede aplicar tambi\u00e9n con rodillo para revestir, con trapeadora o con brocha. Debe aplicarse una pel\u00edcula delgada para mayor econom\u00eda y eficiencia. Deben limpiarse las goteras o pozas del producto. Para las formas de metal, el mejor resultado se obtiene con una aplicaci\u00f3n &#8220;nebulizada&#8221; de FORM OIL.<\/p>\n<p><strong>PRECAUCIONES<\/strong><br \/>\nNO APLIQUE UNA CANTIDAD EXCESIVA DE FORM OIL EN OTRAS FORMAS O EQUIPOS. NO MEZCLE NI DILUYA CON NING\u00daN OTRO COMPUESTO. NO LO USE EN poliestireno expandido (espuma), caucho, l\u00e1tex (o formas de l\u00e1tex hechas de SBR o caucho natural), o formas revestidas de yeso. Lea y siga la informaci\u00f3n de aplicaci\u00f3n, las precauciones y la informaci\u00f3n de la Hoja de Datos de Seguridad antes de su uso.<\/p>\n<p><strong>SALUD Y SEGURIDAD<\/strong><br \/>\nIrritante para los ojos, la piel y las v\u00edas respiratorias. Consulte la <a href=\"https:\/\/www.wrmeadows.com\/MSDS-PDF\/espanol\/3980000sp.pdf\">Hoja de datos de seguridad<\/a> para ver informaci\u00f3n completa sobre salud y seguridad.<\/p>\n<p><strong>INFORMACI\u00d3N LEED<\/strong><br \/>\nPuede ayudar a contribuir a los cr\u00e9ditos LEED:<\/p>\n<ul>\n<li>MRc9: Tratamiento de desechos de construcci\u00f3n y demolici\u00f3n.<\/li>\n<li>EQc2: Materiales de bajas emisiones [SOLO para centros m\u00e9dicos y escuelas (productos aplicados en exteriores)].<\/li>\n<\/ul>\n<p>2018-09<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-foot.jpg\" alt=\"\" width=\"671\" height=\"85\" align=\"BOTTOM\" border=\"0\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.wrmeadows.com\/pics\/esp-footer.jpg\" alt=\"\" width=\"674\" height=\"220\" align=\"BOTTOM\" border=\"0\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FORM OIL est\u00e1 compuesto por un ingrediente qu\u00edmicamente inerte y de alto peso molecular y est\u00e1 orientado a prevenir la uni\u00f3n del concreto a la forma. El agente liberador de forma FORM OIL, cuando se aplica de manera adecuada, es una manera econ\u00f3mica de reducir sustancialmente la posible formaci\u00f3n de agujeros diminutos.<\/p>\n","protected":false},"author":1,"featured_media":63038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[3,199],"tags":[],"class_list":["post-49463","post","type-post","status-publish","format-standard","has-post-thumbnail","category-construction-products","category-concrete-forming-es","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FORM OIL (Espa\u00f1ol) - Agente liberador de forma conforme a la norma VOC - W. R. Meadows<\/title>\n<meta name=\"description\" content=\"FORM OIL est\u00e1 compuesto por un ingrediente qu\u00edmicamente inerte y de alto peso molecular y est\u00e1 orientado a prevenir la uni\u00f3n del concreto a la forma. El agente liberador de forma FORM OIL, cuando se aplica de manera adecuada, es una manera econ\u00f3mica de reducir sustancialmente la posible formaci\u00f3n de agujeros diminutos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FORM OIL (Espa\u00f1ol)\" \/>\n<meta property=\"og:description\" content=\"FORM OIL est\u00e1 compuesto por un ingrediente qu\u00edmicamente inerte y de alto peso molecular y est\u00e1 orientado a prevenir la uni\u00f3n del concreto a la forma. El agente liberador de forma FORM OIL, cuando se aplica de manera adecuada, es una manera econ\u00f3mica de reducir sustancialmente la posible formaci\u00f3n de agujeros diminutos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/\" \/>\n<meta property=\"og:site_name\" content=\"W. R. Meadows\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wrmeadows\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-25T21:17:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T15:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/form-oil-voc-compliant-form-release-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"W. R. MEADOWS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wrmeadows\" \/>\n<meta name=\"twitter:site\" content=\"@wrmeadows\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"W. R. MEADOWS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/\"},\"author\":{\"name\":\"W. R. MEADOWS\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/person\\\/0ffb3012c975c9703745930b937e0fa3\"},\"headline\":\"FORM OIL (Espa\u00f1ol)\",\"datePublished\":\"2021-02-25T21:17:59+00:00\",\"dateModified\":\"2024-01-16T15:54:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/\"},\"wordCount\":780,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/form-oil-voc-compliant-form-release-2.jpg\",\"articleSection\":[\"Construction Products\",\"Form Release Agents\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/\",\"name\":\"FORM OIL (Espa\u00f1ol) - Agente liberador de forma conforme a la norma VOC - W. R. Meadows\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/form-oil-voc-compliant-form-release-2.jpg\",\"datePublished\":\"2021-02-25T21:17:59+00:00\",\"dateModified\":\"2024-01-16T15:54:52+00:00\",\"description\":\"FORM OIL est\u00e1 compuesto por un ingrediente qu\u00edmicamente inerte y de alto peso molecular y est\u00e1 orientado a prevenir la uni\u00f3n del concreto a la forma. El agente liberador de forma FORM OIL, cuando se aplica de manera adecuada, es una manera econ\u00f3mica de reducir sustancialmente la posible formaci\u00f3n de agujeros diminutos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/form-oil-voc-compliant-form-release-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/form-oil-voc-compliant-form-release-2.jpg\",\"width\":738,\"height\":731,\"caption\":\"form-oil-voc-compliant-form-release\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/form-oil-espanol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construction Products\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Construction Liquids\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/construction-liquids-es\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Form Release Agents\",\"item\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/c\\\/construction-products-es\\\/construction-liquids-es\\\/concrete-forming-es\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"FORM OIL (Espa\u00f1ol)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\",\"name\":\"W. R. Meadows\",\"description\":\"Concrete Construction Products Manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#organization\",\"name\":\"W. R. Meadows\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/logo-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wrmeadows.com\\\/wp-content\\\/uploads\\\/logo-3.jpg\",\"width\":709,\"height\":709,\"caption\":\"W. R. Meadows\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wrmeadows\",\"https:\\\/\\\/x.com\\\/wrmeadows\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/w-r-meadows-inc\",\"https:\\\/\\\/www.youtube.com\\\/WrmeadowsTraining\",\"https:\\\/\\\/www.instagram.com\\\/wrmeadowsinc\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wrmeadows.com\\\/es\\\/#\\\/schema\\\/person\\\/0ffb3012c975c9703745930b937e0fa3\",\"name\":\"W. R. MEADOWS\",\"description\":\"W. R. MEADOWS, INC. designs, manufactures, and markets high-quality building materials for today's construction professionals. Products are sold through an authorized distribution network. The family-owned and operated company focuses on product quality, exceptional service, and trusted integrity since its founding in 1926. About Us | Vapor Barriers | Air Barriers | Concrete Expansion Joints | All Construction Products\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FORM OIL (Espa\u00f1ol) - Agente liberador de forma conforme a la norma VOC - W. R. Meadows","description":"FORM OIL est\u00e1 compuesto por un ingrediente qu\u00edmicamente inerte y de alto peso molecular y est\u00e1 orientado a prevenir la uni\u00f3n del concreto a la forma. El agente liberador de forma FORM OIL, cuando se aplica de manera adecuada, es una manera econ\u00f3mica de reducir sustancialmente la posible formaci\u00f3n de agujeros diminutos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/","og_locale":"en_US","og_type":"article","og_title":"FORM OIL (Espa\u00f1ol)","og_description":"FORM OIL est\u00e1 compuesto por un ingrediente qu\u00edmicamente inerte y de alto peso molecular y est\u00e1 orientado a prevenir la uni\u00f3n del concreto a la forma. El agente liberador de forma FORM OIL, cuando se aplica de manera adecuada, es una manera econ\u00f3mica de reducir sustancialmente la posible formaci\u00f3n de agujeros diminutos.","og_url":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/","og_site_name":"W. R. Meadows","article_publisher":"https:\/\/www.facebook.com\/wrmeadows","article_published_time":"2021-02-25T21:17:59+00:00","article_modified_time":"2024-01-16T15:54:52+00:00","og_image":[{"width":738,"height":731,"url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/form-oil-voc-compliant-form-release-2.jpg","type":"image\/jpeg"}],"author":"W. R. MEADOWS","twitter_card":"summary_large_image","twitter_creator":"@wrmeadows","twitter_site":"@wrmeadows","twitter_misc":{"Escrito por":"W. R. MEADOWS","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/#article","isPartOf":{"@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/"},"author":{"name":"W. R. MEADOWS","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/person\/0ffb3012c975c9703745930b937e0fa3"},"headline":"FORM OIL (Espa\u00f1ol)","datePublished":"2021-02-25T21:17:59+00:00","dateModified":"2024-01-16T15:54:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/"},"wordCount":780,"publisher":{"@id":"https:\/\/www.wrmeadows.com\/es\/#organization"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/form-oil-voc-compliant-form-release-2.jpg","articleSection":["Construction Products","Form Release Agents"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/","url":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/","name":"FORM OIL (Espa\u00f1ol) - Agente liberador de forma conforme a la norma VOC - W. R. Meadows","isPartOf":{"@id":"https:\/\/www.wrmeadows.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/#primaryimage"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/form-oil-voc-compliant-form-release-2.jpg","datePublished":"2021-02-25T21:17:59+00:00","dateModified":"2024-01-16T15:54:52+00:00","description":"FORM OIL est\u00e1 compuesto por un ingrediente qu\u00edmicamente inerte y de alto peso molecular y est\u00e1 orientado a prevenir la uni\u00f3n del concreto a la forma. El agente liberador de forma FORM OIL, cuando se aplica de manera adecuada, es una manera econ\u00f3mica de reducir sustancialmente la posible formaci\u00f3n de agujeros diminutos.","breadcrumb":{"@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/#primaryimage","url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/form-oil-voc-compliant-form-release-2.jpg","contentUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/form-oil-voc-compliant-form-release-2.jpg","width":738,"height":731,"caption":"form-oil-voc-compliant-form-release"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wrmeadows.com\/es\/form-oil-espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wrmeadows.com\/es\/"},{"@type":"ListItem","position":2,"name":"Construction Products","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/"},{"@type":"ListItem","position":3,"name":"Construction Liquids","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/construction-liquids-es\/"},{"@type":"ListItem","position":4,"name":"Form Release Agents","item":"https:\/\/www.wrmeadows.com\/es\/c\/construction-products-es\/construction-liquids-es\/concrete-forming-es\/"},{"@type":"ListItem","position":5,"name":"FORM OIL (Espa\u00f1ol)"}]},{"@type":"WebSite","@id":"https:\/\/www.wrmeadows.com\/es\/#website","url":"https:\/\/www.wrmeadows.com\/es\/","name":"W. R. Meadows","description":"Concrete Construction Products Manufacturer","publisher":{"@id":"https:\/\/www.wrmeadows.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wrmeadows.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.wrmeadows.com\/es\/#organization","name":"W. R. Meadows","url":"https:\/\/www.wrmeadows.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/logo-3.jpg","contentUrl":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/logo-3.jpg","width":709,"height":709,"caption":"W. R. Meadows"},"image":{"@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wrmeadows","https:\/\/x.com\/wrmeadows","https:\/\/www.linkedin.com\/company\/w-r-meadows-inc","https:\/\/www.youtube.com\/WrmeadowsTraining","https:\/\/www.instagram.com\/wrmeadowsinc\/"]},{"@type":"Person","@id":"https:\/\/www.wrmeadows.com\/es\/#\/schema\/person\/0ffb3012c975c9703745930b937e0fa3","name":"W. R. MEADOWS","description":"W. R. MEADOWS, INC. designs, manufactures, and markets high-quality building materials for today's construction professionals. Products are sold through an authorized distribution network. The family-owned and operated company focuses on product quality, exceptional service, and trusted integrity since its founding in 1926. About Us | Vapor Barriers | Air Barriers | Concrete Expansion Joints | All Construction Products"}]}},"jetpack_featured_media_url":"https:\/\/www.wrmeadows.com\/wp-content\/uploads\/form-oil-voc-compliant-form-release-2.jpg","_links":{"self":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts\/49463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/comments?post=49463"}],"version-history":[{"count":0,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/posts\/49463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/media\/63038"}],"wp:attachment":[{"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/media?parent=49463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/categories?post=49463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wrmeadows.com\/es\/wp-json\/wp\/v2\/tags?post=49463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}